{"id":22212,"date":"2019-10-03T07:12:04","date_gmt":"2019-10-03T06:12:04","guid":{"rendered":"http:\/\/diariodevurgos.com\/dvwps\/?p=22212"},"modified":"2019-10-03T07:12:04","modified_gmt":"2019-10-03T06:12:04","slug":"el-csr-gamonal-responde-a-las-amenazas-fascistas-e-institucionales","status":"publish","type":"post","link":"https:\/\/diariodevurgos.com\/dvwps\/el-csr-gamonal-responde-a-las-amenazas-fascistas-e-institucionales.php","title":{"rendered":"El CSR Gamonal responde a las amenazas fascistas e institucionales"},"content":{"rendered":"<p class=\"lead\">Frente a la amenaza de desalojo por parte de Fundaci\u00f3n Caja de Burgos y las pintadas neonazis aparecidas en los murales del Centro Social Recuperado, desde el CSR Gamonal se hace un <strong>llamamiento a reponer los murales del exterior del espacio de forma colectiva<\/strong>.<\/p>\n<p>La iniciativa se llevar\u00e1 a cabo este <strong>s\u00e1bado 5 de octubre<\/strong> a partir de las <strong>11:00 horas<\/strong> y supone el primer paso para hacer frente a las amenazas tanto fascistas como institucionales que debe afrontar el centro social de Gamonal.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"aligncenter wp-image-22213 \" src=\"http:\/\/diariodevurgos.com\/dvwps\/wp-content\/uploads\/2019\/10\/REPONER-MURALES-CSR-724x1024.jpg\" alt=\"\" width=\"423\" height=\"599\" srcset=\"https:\/\/diariodevurgos.com\/dvwps\/wp-content\/uploads\/2019\/10\/REPONER-MURALES-CSR-724x1024.jpg 724w, https:\/\/diariodevurgos.com\/dvwps\/wp-content\/uploads\/2019\/10\/REPONER-MURALES-CSR-212x300.jpg 212w, https:\/\/diariodevurgos.com\/dvwps\/wp-content\/uploads\/2019\/10\/REPONER-MURALES-CSR-768x1087.jpg 768w, https:\/\/diariodevurgos.com\/dvwps\/wp-content\/uploads\/2019\/10\/REPONER-MURALES-CSR-370x524.jpg 370w, https:\/\/diariodevurgos.com\/dvwps\/wp-content\/uploads\/2019\/10\/REPONER-MURALES-CSR.jpg 848w\" sizes=\"(max-width: 423px) 100vw, 423px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frente a la amenaza de desalojo por parte de Fundaci\u00f3n Caja de Burgos y las pintadas neonazis aparecidas en los murales del Centro Social Recuperado, desde el CSR Gamonal se hace un llamamiento a reponer los murales del exterior del espacio de forma colectiva. La iniciativa se llevar\u00e1 a cabo este s\u00e1bado 5 de octubre&#8230;  <a href=\"https:\/\/diariodevurgos.com\/dvwps\/el-csr-gamonal-responde-a-las-amenazas-fascistas-e-institucionales.php\" class=\"more-link\" title=\"Read El CSR Gamonal responde a las amenazas fascistas e institucionales\">Read more &raquo;<\/a><\/p>\n","protected":false},"author":2,"featured_media":22213,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31,2,57,78,14,27],"tags":[],"_links":{"self":[{"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/posts\/22212"}],"collection":[{"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/comments?post=22212"}],"version-history":[{"count":1,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/posts\/22212\/revisions"}],"predecessor-version":[{"id":22214,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/posts\/22212\/revisions\/22214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/media\/22213"}],"wp:attachment":[{"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/media?parent=22212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/categories?post=22212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/tags?post=22212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}