{"id":22513,"date":"2019-12-09T17:48:10","date_gmt":"2019-12-09T16:48:10","guid":{"rendered":"http:\/\/diariodevurgos.com\/dvwps\/?p=22513"},"modified":"2019-12-09T17:48:40","modified_gmt":"2019-12-09T16:48:40","slug":"poesia-participativa-a-las-cosas-por-su-nombre","status":"publish","type":"post","link":"https:\/\/diariodevurgos.com\/dvwps\/poesia-participativa-a-las-cosas-por-su-nombre.php","title":{"rendered":"Poes\u00eda participativa: a las cosas por su nombre"},"content":{"rendered":"<p class=\"lead\"><strong>\u201cA las cosas por su nombre\u201d<\/strong> es el l<em>eitmotiv<\/em> de la nueva sesi\u00f3n de poes\u00eda participativa programada por el <a href=\"https:\/\/csrgamonal.ga\/2019\/12\/05\/poesia-a-las-cosas-por-su-nombre\/\">CSR Gamonal<\/a> que tendr\u00e1 lugar el pr\u00f3ximo <strong>mi\u00e9rcoles 11 de diciembre<\/strong> a partir de las <strong>20:00 horas<\/strong>.<\/p>\n<p>Las sesiones de poes\u00eda participativa son una actividad abierta a cualquier persona que quiera participar con la lectura de poemas propios o ajenos, que se realizan de manera mensual en el Centro Social Recuperado.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"aligncenter wp-image-22514 \" src=\"http:\/\/diariodevurgos.com\/dvwps\/wp-content\/uploads\/2019\/12\/poesia_alascosasporsunombre.jpg\" alt=\"\" width=\"478\" height=\"676\" srcset=\"https:\/\/diariodevurgos.com\/dvwps\/wp-content\/uploads\/2019\/12\/poesia_alascosasporsunombre.jpg 608w, https:\/\/diariodevurgos.com\/dvwps\/wp-content\/uploads\/2019\/12\/poesia_alascosasporsunombre-212x300.jpg 212w, https:\/\/diariodevurgos.com\/dvwps\/wp-content\/uploads\/2019\/12\/poesia_alascosasporsunombre-370x523.jpg 370w\" sizes=\"(max-width: 478px) 100vw, 478px\" \/><\/p>\n<p style=\"text-align: center;\">\n","protected":false},"excerpt":{"rendered":"<p>\u201cA las cosas por su nombre\u201d es el leitmotiv de la nueva sesi\u00f3n de poes\u00eda participativa programada por el CSR Gamonal que tendr\u00e1 lugar el pr\u00f3ximo mi\u00e9rcoles 11 de diciembre a partir de las 20:00 horas. Las sesiones de poes\u00eda participativa son una actividad abierta a cualquier persona que quiera participar con la lectura de&#8230;  <a href=\"https:\/\/diariodevurgos.com\/dvwps\/poesia-participativa-a-las-cosas-por-su-nombre.php\" class=\"more-link\" title=\"Read Poes\u00eda participativa: a las cosas por su nombre\">Read more &raquo;<\/a><\/p>\n","protected":false},"author":2,"featured_media":22514,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2,78,103,14,27],"tags":[],"_links":{"self":[{"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/posts\/22513"}],"collection":[{"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/comments?post=22513"}],"version-history":[{"count":1,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/posts\/22513\/revisions"}],"predecessor-version":[{"id":22515,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/posts\/22513\/revisions\/22515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/media\/22514"}],"wp:attachment":[{"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/media?parent=22513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/categories?post=22513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/tags?post=22513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}