{"id":2517,"date":"2009-03-11T16:46:37","date_gmt":"2009-03-11T15:46:37","guid":{"rendered":"http:\/\/diariodevurgos.com\/dvwps\/?p=2517"},"modified":"2009-03-11T16:50:54","modified_gmt":"2009-03-11T15:50:54","slug":"manifestacion-contra-bolonia","status":"publish","type":"post","link":"https:\/\/diariodevurgos.com\/dvwps\/manifestacion-contra-bolonia.php","title":{"rendered":"Manifestaci\u00f3n contra Bolonia"},"content":{"rendered":"<p style=\"text-align: left;\" class=\"lead\">Ma\u00f1ana jueves, d\u00ed\u00ada 12 de marzo, se ha convocado una manifestaci\u00f3n en la Plaza del Cid a las 12:00, con motivo de la lucha contra el Plan Bolonia. Los convocantes son los miembros de la <strong>Asamblea Contra la Mercantilizaci\u00f3n de la Educaci\u00f3n<\/strong><a title=\"ACME\" href=\"http:\/\/www.acmeburgos.org\/\"> (ACME)<\/a> en Burgos.La organizaci\u00f3n de este acto surgi\u00f3 en\u00a0 el encuentro de asambleas contra Bolonia celebrado en Valencia el diciembre pasado.<\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-2518\" title=\"20-11-2008-13-00-08-huelga-y-manifestacion-stop-bolonia-05400\" src=\"http:\/\/diariodevurgos.com\/dvwps\/wp-content\/uploads\/2009\/03\/20-11-2008-13-00-08-huelga-y-manifestacion-stop-bolonia-05400.jpg\" alt=\"20-11-2008-13-00-08-huelga-y-manifestacion-stop-bolonia-05400\" width=\"482\" height=\"118\" srcset=\"https:\/\/diariodevurgos.com\/dvwps\/wp-content\/uploads\/2009\/03\/20-11-2008-13-00-08-huelga-y-manifestacion-stop-bolonia-05400.jpg 800w, https:\/\/diariodevurgos.com\/dvwps\/wp-content\/uploads\/2009\/03\/20-11-2008-13-00-08-huelga-y-manifestacion-stop-bolonia-05400-300x73.jpg 300w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/p>\n<p style=\"text-align: center;\"><!--more--><\/p>\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">Dicha manifestaci\u00f3n transcurrir\u00e1 bajo el lema<em> &#8220;DEBATE P\u00ed\u0161BLICO REAL \u00a1YA!<\/em>&#8220;\u009d; partir\u00e1 de la <strong>Plaza del Cid<\/strong>, pasando por la Subdelegaci\u00f3n del Gobierno, Plaza de Espa\u00f1a, Calle de la Paloma y Paseo del Espol\u00f3n, para terminar en la Plaza mayor.<\/p>\n<p style=\"text-align: left;\">Simult\u00e1neamente, participar\u00e1n en la causa otras ciudades como Madrid, Barcelona, Sevilla, Zaragoza, M\u00e1laga, Valencia, Murcia, Almer\u00ed\u00ada. Le\u00f3n, Oviedo, Santander, Girona, Lleida, Tarragona, Alacant, Castell\u00f3, Mallorca, C\u00e1diz, Salamanca, Cuenca, Huelva, C\u00f3rdoba o Granada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ma\u00f1ana jueves, d\u00ed\u00ada 12 de marzo, se ha convocado una manifestaci\u00f3n en la Plaza del Cid a las 12:00, con motivo de la lucha contra el Plan Bolonia. Los convocantes son los miembros de la Asamblea Contra la Mercantilizaci\u00f3n de la Educaci\u00f3n (ACME) en Burgos.La organizaci\u00f3n de este acto surgi\u00f3 en\u00a0 el encuentro de asambleas&#8230;  <a href=\"https:\/\/diariodevurgos.com\/dvwps\/manifestacion-contra-bolonia.php\" class=\"more-link\" title=\"Read Manifestaci\u00f3n contra Bolonia\">Read more &raquo;<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2,28,14],"tags":[],"_links":{"self":[{"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/posts\/2517"}],"collection":[{"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/comments?post=2517"}],"version-history":[{"count":4,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/posts\/2517\/revisions"}],"predecessor-version":[{"id":2521,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/posts\/2517\/revisions\/2521"}],"wp:attachment":[{"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/media?parent=2517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/categories?post=2517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodevurgos.com\/dvwps\/wp-json\/wp\/v2\/tags?post=2517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}